{"id":1287,"date":"2024-05-14T11:49:41","date_gmt":"2024-05-14T11:49:41","guid":{"rendered":"https:\/\/paveplus.com\/?p=1287"},"modified":"2024-05-28T17:03:52","modified_gmt":"2024-05-28T17:03:52","slug":"bomag-bw-100","status":"publish","type":"post","link":"https:\/\/paveplus.com\/en\/bomag-bw-100\/","title":{"rendered":"Bomag BW 100"},"content":{"rendered":"\n<p>Die Bomag BW 100 ist eine leichte, knickgelenkte Tandemwalze, die sich durch ihre Effizienz und Zuverl\u00e4ssigkeit auszeichnet. Mit einem Eigengewicht von 1700kg und einer Arbeitsbreite von 1,0 m ist sie ideal f\u00fcr eine Vielzahl von Anwendungen. Sie eignet sich besonders f\u00fcr die Verdichtung im Erd- und Asphaltbau, was sie ideal f\u00fcr den Wegebau, Instandsetzungsarbeiten sowie Anschlussarbeiten im Stra\u00dfenbau macht. Alle Funktionen der Tandemwalze k\u00f6nnen \u00fcber das solide mit dem Vorder- und Hinterrahmen verschraubte Knickgelenk bedient und kontrolliert werden.<\/p>\n\n\n\n<p>Dank Fl\u00e4chendeckender dynamischer Verdichtungskontrolle (FDVK) k\u00f6nnen Verdichtungsergebnisse pr\u00e4zise gemessen und dokumentiert werden, was zu einer effizienteren Nutzung der Ressourcen f\u00fchrt. Dar\u00fcber hinaus erm\u00f6glicht FDVK eine Reduzierung der \u00dcberfahrten um bis zu 30%, was zu einer erheblichen Kostenersparnis und Reduzierung des CO2-Aussto\u00dfes beitr\u00e4gt.<\/p>\n\n\n\n<p><strong>Technische Details:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Eigengewicht: 1700kg<\/li>\n\n\n\n<li>Arbeitsbreite: 1,0 m<\/li>\n\n\n\n<li>Transportl\u00e4nge: 2,53 m<\/li>\n\n\n\n<li>Transportbreite: 1,07 m<\/li>\n\n\n\n<li>Transporth\u00f6he: 1,81 m<\/li>\n\n\n\n<li>Vibration: dynamisch<\/li>\n\n\n\n<li>Antrieb: mechanisch<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die Bomag BW 100 ist eine leichte, knickgelenkte Tandemwalze, die sich durch ihre Effizienz und Zuverl\u00e4ssigkeit auszeichnet. Mit einem Eigengewicht von 1700kg und einer Arbeitsbreite von 1,0 m ist sie ideal f\u00fcr eine Vielzahl von Anwendungen. Sie eignet sich besonders f\u00fcr die Verdichtung im Erd- und Asphaltbau, was sie ideal f\u00fcr den Wegebau, Instandsetzungsarbeiten sowie [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":1303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-walzen"],"_links":{"self":[{"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/posts\/1287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/comments?post=1287"}],"version-history":[{"count":2,"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/posts\/1287\/revisions"}],"predecessor-version":[{"id":1317,"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/posts\/1287\/revisions\/1317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/media\/1303"}],"wp:attachment":[{"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/media?parent=1287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/categories?post=1287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paveplus.com\/en\/wp-json\/wp\/v2\/tags?post=1287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}